{"id":108982,"date":"2019-07-17T10:14:08","date_gmt":"2019-07-17T15:14:08","guid":{"rendered":"https:\/\/ideasfrench.wpengine.com\/performance-insights\/"},"modified":"2024-02-14T12:14:48","modified_gmt":"2024-02-14T18:14:48","slug":"performance-insights","status":"publish","type":"page","link":"https:\/\/ideas.com\/fr\/performance-insights\/","title":{"rendered":"Informations sur les performances"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":56,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/solutions.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"tags":[],"class_list":["post-108982","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Analyse de la gestion de revenu | IDeaS SaS<\/title>\n<meta name=\"description\" content=\"L\u2019exploitation de l\u2019analytique avanc\u00e9e SAS\u00ae Visual permet \u00e0 la solution d\u2019\u00e9clairages sur la performance IDeaS d\u2019augmenter vos capacit\u00e9s d\u2019analyse, de reporting et d\u2019action sur vos donn\u00e9es de performance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ideas.com\/fr\/performance-insights\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analyse de la gestion de revenu | IDeaS SaS\" \/>\n<meta property=\"og:description\" content=\"L\u2019exploitation de l\u2019analytique avanc\u00e9e SAS\u00ae Visual permet \u00e0 la solution d\u2019\u00e9clairages sur la performance IDeaS d\u2019augmenter vos capacit\u00e9s d\u2019analyse, de reporting et d\u2019action sur vos donn\u00e9es de performance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ideas.com\/fr\/performance-insights\/\" \/>\n<meta property=\"og:site_name\" content=\"IDeaS\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T18:14:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ideas.com\/wp-content\/uploads\/2024\/12\/ideas_social_image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ideas.com\\\/fr\\\/performance-insights\\\/\",\"url\":\"https:\\\/\\\/ideas.com\\\/fr\\\/performance-insights\\\/\",\"name\":\"Analyse de la gestion de revenu | IDeaS SaS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ideas.com\\\/fr\\\/#website\"},\"datePublished\":\"2019-07-17T15:14:08+00:00\",\"dateModified\":\"2024-02-14T18:14:48+00:00\",\"description\":\"L\u2019exploitation de l\u2019analytique avanc\u00e9e SAS\u00ae Visual permet \u00e0 la solution d\u2019\u00e9clairages sur la performance IDeaS d\u2019augmenter vos capacit\u00e9s d\u2019analyse, de reporting et d\u2019action sur vos donn\u00e9es de performance.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ideas.com\\\/fr\\\/performance-insights\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ideas.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ideas.com\\\/fr\\\/\",\"name\":\"IDeaS\",\"description\":\"Driving Better Revenue\",\"publisher\":{\"@id\":\"https:\\\/\\\/ideas.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ideas.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ideas.com\\\/fr\\\/#organization\",\"name\":\"IDeaS Revenue Solutions\",\"url\":\"https:\\\/\\\/ideas.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ideas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ideas.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/ideas-logo.svg\",\"contentUrl\":\"https:\\\/\\\/ideas.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/ideas-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"IDeaS Revenue Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/ideas.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Analyse de la gestion de revenu | IDeaS SaS","description":"L\u2019exploitation de l\u2019analytique avanc\u00e9e SAS\u00ae Visual permet \u00e0 la solution d\u2019\u00e9clairages sur la performance IDeaS d\u2019augmenter vos capacit\u00e9s d\u2019analyse, de reporting et d\u2019action sur vos donn\u00e9es de performance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ideas.com\/fr\/performance-insights\/","og_locale":"fr_FR","og_type":"article","og_title":"Analyse de la gestion de revenu | IDeaS SaS","og_description":"L\u2019exploitation de l\u2019analytique avanc\u00e9e SAS\u00ae Visual permet \u00e0 la solution d\u2019\u00e9clairages sur la performance IDeaS d\u2019augmenter vos capacit\u00e9s d\u2019analyse, de reporting et d\u2019action sur vos donn\u00e9es de performance.","og_url":"https:\/\/ideas.com\/fr\/performance-insights\/","og_site_name":"IDeaS","article_modified_time":"2024-02-14T18:14:48+00:00","og_image":[{"width":1800,"height":945,"url":"https:\/\/ideas.com\/wp-content\/uploads\/2024\/12\/ideas_social_image.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ideas.com\/fr\/performance-insights\/","url":"https:\/\/ideas.com\/fr\/performance-insights\/","name":"Analyse de la gestion de revenu | IDeaS SaS","isPartOf":{"@id":"https:\/\/ideas.com\/fr\/#website"},"datePublished":"2019-07-17T15:14:08+00:00","dateModified":"2024-02-14T18:14:48+00:00","description":"L\u2019exploitation de l\u2019analytique avanc\u00e9e SAS\u00ae Visual permet \u00e0 la solution d\u2019\u00e9clairages sur la performance IDeaS d\u2019augmenter vos capacit\u00e9s d\u2019analyse, de reporting et d\u2019action sur vos donn\u00e9es de performance.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ideas.com\/fr\/performance-insights\/"]}]},{"@type":"WebSite","@id":"https:\/\/ideas.com\/fr\/#website","url":"https:\/\/ideas.com\/fr\/","name":"IDeaS","description":"Driving Better Revenue","publisher":{"@id":"https:\/\/ideas.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ideas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ideas.com\/fr\/#organization","name":"IDeaS Revenue Solutions","url":"https:\/\/ideas.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ideas.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ideas.com\/wp-content\/uploads\/2021\/08\/ideas-logo.svg","contentUrl":"https:\/\/ideas.com\/wp-content\/uploads\/2021\/08\/ideas-logo.svg","width":1,"height":1,"caption":"IDeaS Revenue Solutions"},"image":{"@id":"https:\/\/ideas.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ideas.com\/fr\/wp-json\/wp\/v2\/pages\/108982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ideas.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ideas.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ideas.com\/fr\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/ideas.com\/fr\/wp-json\/wp\/v2\/comments?post=108982"}],"version-history":[{"count":0,"href":"https:\/\/ideas.com\/fr\/wp-json\/wp\/v2\/pages\/108982\/revisions"}],"wp:attachment":[{"href":"https:\/\/ideas.com\/fr\/wp-json\/wp\/v2\/media?parent=108982"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ideas.com\/fr\/wp-json\/wp\/v2\/tags?post=108982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}